{"id":12133,"date":"2018-01-15T11:10:45","date_gmt":"2018-01-15T13:10:45","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=12133"},"modified":"2018-01-15T11:10:45","modified_gmt":"2018-01-15T13:10:45","slug":"veja-como-foi-o-natal-e-reveillon-de-nossos-plantonistas","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/foto-eventos\/veja-como-foi-o-natal-e-reveillon-de-nossos-plantonistas\/","title":{"rendered":"Veja como foi o Natal e Reveillon de nossos plantonistas!"},"content":{"rendered":"<p>N\u00e3o \u00e9 sempre que conseguimos confraternizar com nossos familiares em datas especiais como o <span id=\"OBJ_PREFIX_DWT2093_com_zimbra_date\" class=\"Object\" role=\"link\"><span id=\"OBJ_PREFIX_DWT2121_com_zimbra_date\" class=\"Object\" role=\"link\">Natal<\/span><\/span> e o Reveillon, mas isso n\u00e3o significa que n\u00e3o podemos passar essas noites ao lado de pessoas queridas que fazem parte de nossas vidas.<\/p>\n<p>Foi assim com nossos colegas que estavam de plant\u00e3o nas noites de 24 e <span id=\"OBJ_PREFIX_DWT2094_com_zimbra_date\" class=\"Object\" role=\"link\"><span id=\"OBJ_PREFIX_DWT2122_com_zimbra_date\" class=\"Object\" role=\"link\">31 de dezembro<\/span><\/span>. O RH Buonny preparou uma ceia deliciosa para que essas ocasi\u00f5es fossem memor\u00e1veis.<\/p>\n<p>Confira s\u00f3 as fotos!<\/p>\n<style>\r\n\/*===== general options =========*\/\r\na {\r\n    box-shadow: none !important;\r\n}\r\n\r\n.view *, .album_categories *, .album_back_button *, #album_disabled_layer {\r\n    font-family: sans-serif, Arial, Verdana, Sylfaen !important;\r\n}\r\n\r\n#album_disabled_layer {\r\n    display: none;\r\n    position: absolute;\r\n    width: 100%;\r\n    height: 100%;\r\n    text-align: center;\r\n    background-color: transparent;\r\n    z-index: 10;\r\n    padding-top: 20px;\r\n    color: #fff;\r\n}\r\n\r\n#album_list_container {\r\n    position: relative;\r\n}\r\n\r\n\/* ====================== album onhover styles ==========================*\/\r\n\r\n#album_list .view {\r\n    -webkit-box-sizing: border-box;\r\n    -moz-box-sizing: border-box;\r\n    -o-box-sizing: border-box;\r\n    display: none;\r\n\r\n}\r\n\r\n.view .mask,\r\n.view .content {\r\n    width: 100%;\r\n    height: 100%;\r\n    position: absolute;\r\n    overflow: hidden;\r\n    top: 0;\r\n    left: 0;\r\n}\r\n\r\n.view h2 {\r\n    text-transform: uppercase;\r\n    color: #fff;\r\n    text-align: center;\r\n    position: relative;\r\n    font-size: 17px;\r\n    font-family: Raleway, serif;\r\n    padding: 10px;\r\n    \/*background: rgba(0, 0, 0, 0.8);*\/\r\n    margin: 20px 0 0 0;\r\n\r\n}\r\n\r\n.album_back_button a, .view a {\r\n    text-decoration: none !important;\r\n}\r\n\r\n.view p {\r\n    font-family: Merriweather, serif;\r\n    font-style: italic;\r\n    font-size: 14px;\r\n    position: relative;\r\n    color: #fff;\r\n    padding: 0px 20px 0px;\r\n    text-align: center;\r\n\r\n}\r\n\r\n.view a.info {\r\n    display: inline-block;\r\n    text-decoration: none;\r\n    font-size: 13px;\r\n    padding: 2px 14px;\r\n    margin-bottom: 3px;\r\n    background: #000;\r\n    color: #fff;\r\n    font-family: Raleway, serif;\r\n    text-transform: uppercase;\r\n    box-shadow: 0 0 1px #000\r\n}\r\n\r\n.mask-text h2 {\r\n    font-size: 20px !important;\r\n}\r\n\r\n.view a.info:hover {\r\n    box-shadow: 0 0 5px #000\r\n}\r\n\r\n.view .mask-bg {\r\n    height: 100%;\r\n}\r\n\r\n.view .album_social {\r\n    color: #fff;\r\n    position: absolute;\r\n    bottom: 3px;\r\n    left: 3px;\r\n    border: 1px solid #ffffff;\r\n    -webkit-border-radius: 3px;\r\n    -moz-border-radius: 3px;\r\n    border-radius: 3px;\r\n    padding: 3px 5px;\r\n\r\n}\r\n\r\n.view .album_social:active, .view .album_social:focus, .view .album_social:hover {\r\n    color: #ffffff;\r\n    outline: none;\r\n}\r\n\r\n\/*1*\/\r\n\r\n.view .info {\r\n    margin-top: 5px;\r\n}\r\n\r\n.view-first .mask {\r\n    opacity: 0;\r\n    background-color: rgba(0, 0, 0, 0.7);\r\n    transition: all 0.4s ease-in-out;\r\n\r\n}\r\n\r\n.view-first h2 {\r\n    transform: translateY(-100px);\r\n    opacity: 0;\r\n    font-family: Raleway, serif;\r\n    transition: all 0.2s ease-in-out;\r\n}\r\n\r\n.view-first p {\r\n    transform: translateY(100px);\r\n    opacity: 0;\r\n    transition: all 0.2s linear;\r\n}\r\n\r\n.view-first a.info {\r\n    opacity: 0;\r\n    transition: all 0.2s ease-in-out;\r\n}\r\n\r\n\/* *\/\r\n\r\n.view-first:hover img {\r\n    \/*transform: scale(1.1);*\/\r\n}\r\n\r\n.view-first:hover .mask {\r\n    opacity: 1;\r\n}\r\n\r\n.view-first:hover h2,\r\n.view-first:hover p,\r\n.view-first:hover a.info {\r\n    opacity: 1;\r\n    transform: translateY(0px);\r\n}\r\n\r\n.view-first:hover p {\r\n    transition-delay: 0.1s;\r\n}\r\n\r\n.view-first:hover a.info {\r\n    transition-delay: 0.2s;\r\n}\r\n\r\n\/*2*\/\r\n.view-second img {\r\n    -webkit-filter: grayscale(0) blur(0);\r\n    filter: grayscale(0) blur(0);\r\n    -webkit-transition: .3s ease-in-out;\r\n    transition: .3s ease-in-out;\r\n}\r\n\r\n.view-second .mask {\r\n    background-color: rgba(226, 200, 127, 0.2);\r\n    transition: all 0.5s linear;\r\n    opacity: 0;\r\n}\r\n\r\n.view-second h2 {\r\n    background: transparent;\r\n    margin: 20px 40px 0px 40px;\r\n    transform: scale(0);\r\n    color: #333;\r\n    transition: all 0.5s linear;\r\n    opacity: 0;\r\n}\r\n\r\n.view-second p {\r\n    opacity: 0;\r\n    transform: scale(0);\r\n    transition: all 0.5s linear;\r\n}\r\n\r\n.view-second a.info {\r\n    opacity: 0;\r\n    transform: scale(0);\r\n    transition: all 0.5s linear;\r\n}\r\n\r\n.view-second:hover img {\r\n    -webkit-filter: grayscale(100%) blur(3px);\r\n    filter: grayscale(100%) blur(3px);\r\n}\r\n\r\n.view-second:hover .mask {\r\n    opacity: 1;\r\n}\r\n\r\n.view-second:hover h2,\r\n.view-second:hover p,\r\n.view-second:hover a.info {\r\n    transform: scale(1);\r\n    opacity: 1;\r\n}\r\n\r\n.view-second img {\r\n    -webkit-filter: grayscale(0) blur(0);\r\n    filter: grayscale(0) blur(0);\r\n    -webkit-transition: .3s ease-in-out;\r\n    transition: .3s ease-in-out;\r\n}\r\n\r\n.view-second:hover img {\r\n    -webkit-filter: grayscale(100%) blur(3px);\r\n    filter: grayscale(100%) blur(3px);\r\n}\r\n\r\n\/*3*\/\r\n\r\n.view-third img {\r\n    transform: scaleY(1);\r\n    transition: all .7s ease-in-out;\r\n}\r\n\r\n.view-third a.info {\r\n    opacity: 0;\r\n    transform: scale(0);\r\n    transition: all 0.5s linear;\r\n}\r\n\r\n.view-third:hover img {\r\n    -webkit-transform: scale(10);\r\n    transform: scale(10);\r\n    opacity: 0;\r\n}\r\n\r\n.view-third:hover .mask {\r\n    opacity: 1;\r\n}\r\n\r\n.view-third:hover h2,\r\n.view-third:hover p,\r\n.view-third:hover a.info {\r\n    transform: scale(1);\r\n    opacity: 1;\r\n}\r\n\r\n\/* ==== view 4 ===*\/\r\n\r\n.view-forth-wrapper {\r\n    overflow: hidden;\r\n    position: relative !important;\r\n    height: 100%;\r\n    \/* cursor: pointer;*\/\r\n}\r\n\r\n.view-forth img {\r\n    max-width: 100%;\r\n    position: relative;\r\n    top: 0;\r\n    -webkit-transition: all 600ms cubic-bezier(0.645, 0.045, 0.355, 1);\r\n    transition: all 600ms cubic-bezier(0.645, 0.045, 0.355, 1);\r\n}\r\n\r\n.view-forth .mask {\r\n    position: absolute;\r\n    width: 100%;\r\n    \/*    height: 70px;*\/\r\n    \/*    bottom: -70px;*\/\r\n    height: 50%;\r\n    bottom: -50%;\r\n    -webkit-transition: all 300ms cubic-bezier(0.645, 0.045, 0.355, 1);\r\n    transition: all 300ms cubic-bezier(0.645, 0.045, 0.355, 1);\r\n    top: inherit;\r\n}\r\n\r\n.view-forth:hover .mask {\r\n    bottom: 0;\r\n}\r\n\r\n.view-forth:hover img {\r\n    top: -30px;\r\n}\r\n\r\n\/*==  view 5 ==*\/\r\n\r\n.view-fifth .view-fifth-wrapper,\r\n.view-fifth .view-fifth-wrapper img {\r\n    display: block;\r\n    position: relative;\r\n}\r\n\r\n.view-fifth .view-fifth-wrapper {\r\n    overflow: hidden;\r\n    height: 100%;\r\n}\r\n\r\n.view-fifth .view-fifth-wrapper .mask {\r\n    display: none;\r\n    position: absolute;\r\n    background: #333;\r\n    background: rgba(75, 75, 75, 0.7);\r\n    width: 100%;\r\n    height: 100%;\r\n}\r\n\r\n\/* ====================== album category styles ==========================*\/\r\n\r\n#filters {\r\n    margin: 1% 0;\r\n    padding: 0;\r\n    list-style: none;\r\n    list-style-type: none !important;\r\n\r\n}\r\n\r\n#filters li {\r\n    float: left;\r\n    list-style-type: none !important;\r\n}\r\n\r\n#filters li:first-child span {\r\n    margin-left: 0px;\r\n}\r\n\r\n#filters li span {\r\n    display: block;\r\n    text-decoration: none;\r\n    cursor: pointer;\r\n}\r\n\r\n.album_categories {\r\n    list-style-type: none;\r\n    margin: 0;\r\n    padding: 0;\r\n    overflow: hidden;\r\n    padding-top: 5px;\r\n}\r\n\r\n\/*=========  sharing buttons  ============*\/\r\n\r\n.album_socials {\r\n    position: relative;\r\n    top: 3px;\r\n    width: 100px;\r\n    height: 28px;\r\n    margin: 0 auto;\r\n}\r\n\r\n.album_socials .rwd-share-buttons {\r\n    top: 0px !important;\r\n    width: 100% !important;\r\n    margin: 0px !important;\r\n}\r\n\r\n.album_socials a {\r\n    text-decoration: underline !important;\r\n}\r\n\r\n.gallery_images, .album_image_place {\r\n    margin-top: 15px;\r\n    margin-top: 15px;\r\n}\r\n\r\n#rwd-share-facebook:hover {\r\n    background-position: 0 -31px !important;\r\n}\r\n\r\n#rwd-share-twitter:hover {\r\n    background-position: -31px 32px !important;\r\n}\r\n\r\n#rwd-share-googleplus:hover {\r\n    background-position: -66px -31px !important;\r\n}\r\n\r\n.rwd-share-buttons li, .rwd-share-buttons li a {\r\n    width: 26px !important;\r\n    border: 0px !important;\r\n}\r\n\r\n.rwd-share-buttons {\r\n    top: 0 !important;\r\n}\r\n\r\n.img_link_btn {\r\n    position: absolute;\r\n    z-index: 99999;\r\n    bottom: 0;\r\n    left: 0;\r\n    right: 0;\r\n    width: 100%;\r\n    padding: 8px;\r\n}\r\n\r\n.rwd-title {\r\n    padding: 10px 0px !important;\r\n}\r\n\r\n@media only screen and (max-width: 475px) {\r\n    .rwd-share-buttons {\r\n        top: -25px !important;\r\n    }\r\n\r\n    .rwd-title-text {\r\n        line-height: 15px;\r\n    }\r\n}\r\n\r\n\/*=========  hover style ===========*\/\r\n\r\n#hover {\r\n    color: rgba(188, 175, 204, 0.9);\r\n}\r\n\r\nh2#testimonials {\r\n    color: #fffae3;\r\n}\r\n\r\ndiv#all {\r\n    width: 100%;\r\n    height: 100%;\r\n}\r\n\r\n.view img {\r\n    height: auto;\r\n}\r\n\r\n.view {\r\n    color: #fff;\r\n    margin: 0 10px 10px 0;\r\n    overflow: hidden;\r\n    position: relative;\r\n    text-align: center;\r\n    float: left;\r\n    cursor: default;\r\n    border: 1px solid #ccc;\r\n}\r\n\r\n.view-wrapper {\r\n    height: 100%;\r\n}\r\n\r\n.view img {\r\n    display: block;\r\n    position: relative;\r\n    transition: all 0.2s linear;\r\n    height: 100%;\r\n    width: auto;\r\n    max-width: 100%;\r\n    margin: 0 auto;\r\n}\r\n\r\n.mask-text h2 {\r\n    font-size: 20px !important;\r\n    margin-top: 20px !important;\r\n}\r\n\r\n\/* view 1 *\/\r\n\r\n.view-first .text-category, .view-first .mask-text h2, .view-first .mask-text p {\r\n    color: #fff;\r\n}\r\n\r\n\/*  view 2 *\/\r\n.view-second .text-category, .view-second .mask-text h2, .view-second p {\r\n    color: #333;\r\n}\r\n\r\n.view-second .mask-text h2 {\r\n    border-bottom: 1px solid #333;\r\n}\r\n\r\n\/* view 3*\/\r\n.view-third .mask {\r\n    background-color: #ccc;\r\n    transition: all 0.5s linear;\r\n    opacity: 0;\r\n    color: #333;\r\n}\r\n\r\n.view-third h2 {\r\n    border-bottom: 1px solid #333;\r\n    background: transparent;\r\n    margin: 20px 40px 0px 40px;\r\n    transform: scale(0);\r\n    color: #333;\r\n    transition: all 0.5s linear;\r\n    opacity: 0;\r\n}\r\n\r\n.view-third p {\r\n    color: #333;\r\n    opacity: 0;\r\n    transform: scale(0);\r\n    transition: all 0.5s linear;\r\n}\r\n\r\n.view-third .text-category {\r\n    color: #333;\r\n}\r\n\r\n\/* view 4 *\/\r\n\r\n.view-forth .mask-bg {\r\n    background: #333;\r\n    width: 100%;\r\n    height: 100%;\r\n    position: absolute;\r\n    top: 0;\r\n    left: 0;\r\n}\r\n\r\n.view-forth .mask-text {\r\n    color: #fff;\r\n    position: relative;\r\n    z-index: 500;\r\n    padding: 5px 8px;\r\n}\r\n\r\n.view-forth .mask-text h2 {\r\n    margin: 0px;\r\n    font-size: 13px;\r\n    padding: 2px;\r\n    color: #fff;\r\n}\r\n\r\n.view-forth .mask-text h2:hover {\r\n    cursor: pointer;\r\n}\r\n\r\n.view-forth .text-category {\r\n    display: block;\r\n    font-size: 15px;\r\n    color: #fff;\r\n}\r\n\r\n.view-forth p {\r\n    color: #fff;\r\n}\r\n\r\n\/* view 5 *\/\r\n.view-fifth .text-category, .view-fifth .text-category *, .view-fifth .mask-text h2, .view-fifth .mask-text p {\r\n    color: #fff;\r\n}\r\n\r\n<\/style>\r\n    <input type=\"hidden\" name=\"view_style\" value=\"view-first\">\r\n    <section id=\"thumbwrapper47\" class=\"gallery-img-content\"\r\n             data-gallery-id=\"47\" data-content-per-page=\"5\"\r\n             data-rating-type=\"off\">\r\n        <input type=\"hidden\" class=\"pagenum\" value=\"1\"\/>\r\n        <ul id=\"huge_it_gallery47\" class=\"huge_it_gallery view-thumbnails\">\r\n            <li id=\"fullPreview\"><\/li>\r\n                        <input type=\"hidden\" id=\"total\" value=\"2\"\/>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20171231-WA0005.jpeg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20171231-WA0005-576x1024.jpeg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20180109-WA0008.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20180109-WA0008-1024x768.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20180109-WA0011.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/IMG-20180109-WA0011-768x1024.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/26219114_2172723032753844_8110805827042615845_n.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/26219114_2172723032753844_8110805827042615845_n.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/26195801_2172723099420504_6653009273628702839_n.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/26195801_2172723099420504_6653009273628702839_n.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/25995083_2164166503609497_7957757013592299499_n.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/25995083_2164166503609497_7957757013592299499_n.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                            <div class=\"huge_it_big_li view  view-first\">\r\n                    <div class=\"view-first-wrapper view-wrapper\">\r\n\r\n                        \r\n                                <a class=\"gallery_group47\" href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/25660275_2164166520276162_2105889809946485459_n.jpg\"\r\n                                   title=\"\">\r\n                                    <img\r\n                                            src=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2018\/01\/25660275_2164166520276162_2105889809946485459_n.jpg\"\r\n                                            alt=\"\"\/>\r\n                                    <div class=\"mask\">\r\n                                        <div class=\"mask-text\">\r\n                                                                                        <span class=\"text-category\"><\/span>\r\n                                        <\/div>\r\n                                        <div class=\"mask-bg\"><\/div>\r\n                                    <\/div>\r\n                                <\/a>\r\n\r\n                                                    <\/div>\r\n                                    <\/div>\r\n                    <\/ul>\r\n            <\/section>\r\n\r\n<style>\r\nsection #huge_it_gallery47 {\r\n    padding: 28px !important;\r\n    min-width: 100%;\r\n    width: 100%;\r\n    min-height: 100%;\r\n    text-align: center;\r\n    margin: 0;\r\n    margin-bottom: 30px;\r\n  background-color: #333333; box-shadow: 0 0 10px;}\r\n#huge_it_gallery47 .huge_it_big_li {\r\n    overflow:hidden;\r\n    width: 100%;\r\n    max-width: 242px;\r\n    height: 152px;\r\n    margin: 1px -1px !important;\r\n    border-radius: 5px;\r\n    padding:0 !important;\r\n    border-radius: 5px;\r\n    border: 1px solid #444444;\r\n    box-sizing: border-box;\r\n    position: relative;\r\n    display: inline-block;\r\n}\r\n#huge_it_gallery47 li img {\r\n    width: 100%;\r\n    max-width: 240px;\r\n    height: 150px;\r\n    margin:0 !important;\r\n    border-radius: 0px;\r\n}\r\nsection #huge_it_gallery47 li .overLayer ul li h2,\r\nsection #huge_it_gallery47 li .infoLayer ul li h2 {\r\n    font-size: 16px;\r\n    color: #FFFFFF;\r\n}\r\nsection #huge_it_gallery47 li .infoLayer ul li p {\r\n    color: #FFFFFF;\r\n}\r\nsection #huge_it_gallery47 li .overLayer,\r\nsection #huge_it_gallery47 li .infoLayer {\r\n    -webkit-transition: opacity 0.3s linear;\r\n    -moz-transition: opacity 0.3s linear;\r\n    -ms-transition: opacity 0.3s linear;\r\n    -o-transition: opacity 0.3s linear;\r\n    transition: opacity 0.3s linear;\r\n    width: 100%;\r\n    max-width: 242px;\r\n    height: 152px;\r\n    position: absolute;\r\n    text-align: center;\r\n    opacity: 0;\r\n    top: 0;\r\n    left: 0;\r\n    z-index: 4;\r\n    max-height: 100%;\r\n    border-radius: 0px;\r\n}\r\nsection #huge_it_gallery47 li a {\r\n    position: absolute;\r\n    display: block;\r\n    width: 100%;\r\n    max-width: 242px;\r\n    height: 152px;\r\n    top: 0;\r\n    left: 0;\r\n    z-index: 6;\r\n    max-height: 100%;\r\n}\r\nli#fullPreview{\r\n    list-style: none;\r\n}\r\n.load_more3 {\r\n    margin: 10px 0;\r\n    position:relative;\r\n    text-align:center;\r\n    width:100%;\r\n}\r\n.load_more_button3 {\r\n    border-radius: 10px;\r\n    display:inline-block;\r\n    padding:5px 15px;\r\n    font-size:19px !important;;\r\n    color:#CCCCCC !important;;\r\n    background:#333333 !important;\r\n    cursor:pointer;\r\n}\r\n.load_more_button3:hover{\r\n    color:#D9D9D9 !important;\r\n    background:#8F827C !important;\r\n}\r\n.loading3 {\r\n    display:none;\r\n}\r\n.paginate3{\r\n    font-size:22px !important;\r\n    color:#0A0202 !important;\r\n    text-align: center;\r\n}\r\n.paginate3 a{\r\n    border-bottom: none !important;\r\n}\r\n.icon-style3{\r\n    font-size: 22px !important;\r\n    color:#333333 !important;\r\n}\r\n.clear{\r\n    clear:both;\r\n}\r\nsection #huge_it_gallery47 li:hover .overLayer {\r\n    -webkit-transition: opacity 0.3s linear;\r\n    -moz-transition: opacity 0.3s linear;\r\n    -ms-transition: opacity 0.3s linear;\r\n    -o-transition: opacity 0.3s linear;\r\n    transition: opacity 0.3s linear;\r\n    opacity: 0.801;\r\n    display: block;\r\n    background: #CCCCCC;\r\n}\r\nsection #huge_it_gallery47 li:hover .infoLayer {\r\n    -webkit-transition: opacity 0.3s linear;\r\n    -moz-transition: opacity 0.3s linear;\r\n    -ms-transition: opacity 0.3s linear;\r\n    -o-transition: opacity 0.3s linear;\r\n    transition: opacity 0.3s linear;\r\n    opacity: 1;\r\n    display: block;\r\n}\r\nsection #huge_it_gallery47 p {text-align:center;}\r\n\r\n.view {float:none;}\r\n<\/style>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o \u00e9 sempre que conseguimos confraternizar com nossos familiares em datas especiais como o Natal e o Reveillon, mas isso n\u00e3o significa que n\u00e3o podemos passar essas noites ao lado de pessoas queridas que fazem parte de nossas vidas. Foi assim com nossos colegas que estavam de plant\u00e3o nas noites de 24 e 31 de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12133"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12133"}],"version-history":[{"count":2,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12133\/revisions"}],"predecessor-version":[{"id":12144,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12133\/revisions\/12144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/12143"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}