{"id":12207,"date":"2018-01-24T15:25:37","date_gmt":"2018-01-24T17:25:37","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=12207"},"modified":"2018-01-29T11:28:55","modified_gmt":"2018-01-29T13:28:55","slug":"buonny-patrocina-escola-de-samba-que-homenageara-caminhoneiros","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/por-dentro\/imprensa\/buonny-patrocina-escola-de-samba-que-homenageara-caminhoneiros\/","title":{"rendered":"Buonny patrocina escola de samba Rosas de Ouro"},"content":{"rendered":"<div class=\"entry-content\">\n<p>A convite do Sindicam (Sindicato dos Transportadores Rodovi\u00e1rios Aut\u00f4nomos de Carga em Geral do Estado de S\u00e3o Paulo), a Buonny Projetos de Riscos e Servi\u00e7os Securit\u00e1rios est\u00e1 patrocinando o desfile da escola de samba paulistana Rosas de Ouro. A agremia\u00e7\u00e3o levar\u00e1 para o samb\u00f3dromo o samba enredo \u201cPelas estradas da vida, sonhos e aventuras de um her\u00f3i brasileiro\u201d.<\/p>\n<p>Entre outras a\u00e7\u00f5es, a marca Buonny, bem como do Sindicam e Fetrabens, ter\u00e3o destaque durante os ensaios nos dias 24 e 31 de janeiro.<\/p>\n<p>O samba, desenvolvido pelo carnavalesco Andr\u00e9 Machado, contar\u00e1 a vida e o dia a dia dos caminhoneiros, que trafegam pelas estradas brasileiras. O desfile acontecer\u00e1 no dia 9 de fevereiro de 2018, no Samb\u00f3dromo do Anhembi, em S\u00e3o Paulo.<\/p>\n<p><em>\u201c\u00c9 uma honra para n\u00f3s incentivar a cultura popular e um tema t\u00e3o rico como a vida dos caminhoneiros. Sabemos o quanto eles s\u00e3o fundamentais para as nossas vidas e para a economia brasileira; sem o trabalho deles, t\u00e3o importante, nosso Pa\u00eds para\u201d<\/em>, diz Cyro Buonavoglia, presidente do Grupo Buonny.<\/p>\n<p>Veja abaixo o samba enredo completo:<\/p>\n<p><video id=\"videoCentral\" src=\"http:\/\/naboleia.com.br\/wp-content\/uploads\/2018\/01\/Rosas-de-Ouro-homenagem-ao-dia-a-dia-dos-caminhoneiros.mp4\" poster=\"http:\/\/naboleia.com.br\/wp-content\/uploads\/2018\/01\/5d2bf41fa9b3387b125bffc354a289a5_800.jpg\" controls=\"controls\" width=\"853\" height=\"480\" data-mce-fragment=\"1\"><\/video><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Para ler a mat\u00e9ria, <a href=\"http:\/\/naboleia.com.br\/buonny-patrocina-escola-de-samba-que-homenageara-caminhoneiros\/\">clique aqui.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A convite do Sindicam (Sindicato dos Transportadores Rodovi\u00e1rios Aut\u00f4nomos de Carga em Geral do Estado de S\u00e3o Paulo), a Buonny Projetos de Riscos e Servi\u00e7os Securit\u00e1rios est\u00e1 patrocinando o desfile da escola de samba paulistana Rosas de Ouro. A agremia\u00e7\u00e3o levar\u00e1 para o samb\u00f3dromo o samba enredo \u201cPelas estradas da vida, sonhos e aventuras de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12224,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[393,392],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12207"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12207"}],"version-history":[{"count":4,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12207\/revisions"}],"predecessor-version":[{"id":12228,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12207\/revisions\/12228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/12224"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}