{"id":12761,"date":"2018-05-21T14:07:46","date_gmt":"2018-05-21T17:07:46","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=12761"},"modified":"2018-05-21T17:47:43","modified_gmt":"2018-05-21T20:47:43","slug":"dicas-para-evitar-acidentes","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/por-dentro\/imprensa\/dicas-para-evitar-acidentes\/","title":{"rendered":"Dicas para evitar acidentes"},"content":{"rendered":"<h5><strong>Gerenciadora de riscos adere ao Maio Amarelo e enfatiza a import\u00e2ncia da seguran\u00e7a na condu\u00e7\u00e3o de ve\u00edculos de carga<\/strong><\/h5>\n<div class=\"post-body\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft featured_image wp-post-image\" src=\"http:\/\/revistasegurototal.com.br\/wp-content\/uploads\/2018\/05\/Buonny-d\u00e1-cinco-dicas-para-evitar-acidentes-no-transporte-de-cargas-292x262.jpg\" alt=\"Buonny d\u00e1 cinco dicas para evitar acidentes no transporte de cargas\" width=\"292\" height=\"262\" \/><\/p>\n<p class=\"post-meta\"><span class=\"post-date\">15\/05\/2018<\/span><\/p>\n<p>A Buonny\u00a0<a href=\"http:\/\/www.imcgrupo.com\/link.php?code=bDpodHRwJTNBJTJGJTJGd3d3LmJ1b25ueS5jb20uYnIlMkY6MzM2NjQzNDUyNTpzZXJnaW9AcmV2aXN0YXNlZ3Vyb3RvdGFsLmNvbS5icjpkN2Y2MDUwNzk1MjY5ZTU0ZTZhMTViMTkxOGMzNTgzYWUx\"> Projetos de Riscos e Servi\u00e7os Securit\u00e1rios<\/a>, que atua h\u00e1 mais de 20 anos no setor de gerenciamento de riscos em transporte de cargas, est\u00e1 aderindo ao <a href=\"http:\/\/www.imcgrupo.com\/link.php?code=bDpodHRwJTNBJTJGJTJGd3d3Lm1haW9hbWFyZWxvLmNvbSUyRjozMzY2NDM0NTI1OnNlcmdpb0ByZXZpc3Rhc2VndXJvdG90YWwuY29tLmJyOjMxZWNhYzhkMzk5ZTQ4ZTZhMjBiMTcyNjIyZTA1Zjk2YWY=\">Movimento Maio Amarelo<\/a>, coordenado entre o Poder P\u00fablico e a sociedade civil, com o objetivo de despertar a sociedade sobre a import\u00e2ncia da seguran\u00e7a vi\u00e1ria.<\/p>\n<p>De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), cerca de 1,25 milh\u00e3o de pessoas morrem, no mundo, por ano em acidentes de tr\u00e2nsito. Mais de 90% dos acidentes s\u00e3o causados por falha humana.<\/p>\n<p>Al\u00e9m disso, o Brasil \u00e9 o quarto pa\u00eds com maior \u00edndice de acidentes no tr\u00e2nsito e gasta R$ 60 bilh\u00f5es por ano com isso, de acordo com o Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea).<\/p>\n<p>Diante desse cen\u00e1rio e com base em sua experi\u00eancia de mais de 20 anos na \u00e1rea de gerenciamento de riscos em log\u00edstica e transportes, a Buonny destaca cinco maiores causas de acidentes envolvendo caminh\u00f5es no Brasil.<\/p>\n<h2>1. Grandes dist\u00e2ncias percorridas em uma \u00fanica viagem<\/h2>\n<p>O Brasil possui um territ\u00f3rio extenso e, por isso, o ve\u00edculo e o motorista ficam expostos a riscos por muito tempo. Al\u00e9m da dist\u00e2ncia, existe a press\u00e3o pelo cumprimento de prazos, que contribui para o aumento de acidentes envolvendo ve\u00edculos de carga.<\/p>\n<h2>2. Descumprimento da Lei do Caminhoneiro<\/h2>\n<p>Em geral, o repouso semanal, intervalos para descanso, paradas para almo\u00e7o e jornada m\u00e1xima de trabalho s\u00e3o as regras mais desrespeitadas da Lei 13.103, popularmente conhecida como a Lei do Caminhoneiro, criada para dar mais seguran\u00e7a e aumentar a qualidade de vida dos motoristas. Por\u00e9m, se n\u00e3o for respeitada, pode trazer graves consequ\u00eancias, uma vez que sono, fome e fadiga geram perda de reflexo significativa. Dessa forma, a seguran\u00e7a do motorista e de todos que cruzam seu caminho fica comprometida.<\/p>\n<h2>3. Caminh\u00f5es com excesso de carga<\/h2>\n<p>Apesar da fiscaliza\u00e7\u00e3o exercida pelos \u00f3rg\u00e3os governamentais, n\u00e3o \u00e9 raro encontrarmos caminh\u00f5es trafegando com peso acima do limite permitido. Esse tipo de situa\u00e7\u00e3o, al\u00e9m de prejudicar a infraestrutura das estradas, \u00e9 um fator de risco e contribui para a ocorr\u00eancia de acidentes.<\/p>\n<h2>4. Imprud\u00eancia dos motoristas<\/h2>\n<p>O comportamento do condutor \u00e9 determinante para a ocorr\u00eancia de acidentes. Os problemas s\u00e3o muitos: ultrapassagens em locais proibidos, alta velocidade, falta de sinaliza\u00e7\u00e3o, entre outros. Tudo isso aumenta a inseguran\u00e7a nas rodovias e causa in\u00fameros sinistros, muitas vezes fatais.<\/p>\n<h2>5. Rotas mal planejadas<\/h2>\n<p>A m\u00e1 conserva\u00e7\u00e3o das estradas e rodovias brasileiras \u00e9 um dos maiores desencadeadores de acidentes de tr\u00e2nsito. S\u00e3o buracos, m\u00e1 sinaliza\u00e7\u00e3o ou mesmo lombadas mal posicionadas. Por isso, \u00e9 imprescind\u00edvel que a opera\u00e7\u00e3o de transporte seja feita com rotas planejadas, levando em considera\u00e7\u00e3o todas as adversidades e obst\u00e1culos que as estradas apresentam.<\/p>\n<p>Para aderir ao movimento, acesse: <a href=\"http:\/\/www.maioamarelo.com\">www.maioamarelo.com<\/a><\/p>\n<\/div>\n<p>Mat\u00e9ria na \u00edntegra <a href=\"http:\/\/revistasegurototal.com.br\/buonny-dicas-transporte-de-cargas\/\">aqui.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gerenciadora de riscos adere ao Maio Amarelo e enfatiza a import\u00e2ncia da seguran\u00e7a na condu\u00e7\u00e3o de ve\u00edculos de carga 15\/05\/2018 A Buonny\u00a0 Projetos de Riscos e Servi\u00e7os Securit\u00e1rios, que atua h\u00e1 mais de 20 anos no setor de gerenciamento de riscos em transporte de cargas, est\u00e1 aderindo ao Movimento Maio Amarelo, coordenado entre o Poder &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12768,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12761"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12761"}],"version-history":[{"count":4,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12761\/revisions"}],"predecessor-version":[{"id":12769,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12761\/revisions\/12769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/12768"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}