{"id":13225,"date":"2018-07-24T12:23:18","date_gmt":"2018-07-24T15:23:18","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=13225"},"modified":"2018-07-23T14:12:51","modified_gmt":"2018-07-23T17:12:51","slug":"fique-atento-as-sinalizacoes-e-as-normas-internas-da-empresa","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/seguranca\/fique-atento-as-sinalizacoes-e-as-normas-internas-da-empresa\/","title":{"rendered":"Fique atento \u00e0s sinaliza\u00e7\u00f5es e as normas internas da empresa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Nas instala\u00e7\u00f5es do grupo Buonny, voc\u00ea encontrar\u00e1 placas e outras sinaliza\u00e7\u00f5es nos ambientes de trabalho que tem como objetivo<\/span><b> alertar<\/b><span style=\"font-weight: 400;\">, voc\u00ea e os visitantes no local, sobre <\/span><b>os riscos existentes ali e outras informa\u00e7\u00f5es imprescind\u00edveis para seguran\u00e7a<\/b><span style=\"font-weight: 400;\"> no local. \u00a0Fique atento \u00e0 todas as sinaliza\u00e7\u00f5es para garantir a sua seguran\u00e7a em casos de emerg\u00eancia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em casos de inc\u00eandio,<\/span><b> temos detectores de fuma\u00e7a, alarmes de inc\u00eandio e extintores em pontos estrat\u00e9gicos<\/b><span style=\"font-weight: 400;\"> para garantir a sua seguran\u00e7a, identifique onde est\u00e3o os mais pr\u00f3ximos de voc\u00ea e fique atento para iniciar a evacua\u00e7\u00e3o ao ouvir o alarme de inc\u00eandio.<\/span><\/p>\n<h3>C\u00f3digo de Conduta<\/h3>\n<p>Pensando em um ambiente saud\u00e1vel de trabalho, o C\u00f3digo de Conduta \u00e9 um conjunto de princ\u00edpios e valores que serve como um guia de refer\u00eancia aos colaboradores possam avaliar e auxiliar na escolha da melhor linha de conduta. O mesmo\u00a0est\u00e1 dispon\u00edvel online <a href=\"http:\/\/info.buonny.com.br\/index.php\/portal-compliance\/codigo-conduta\/\">aqui<\/a>\u00a0para todos os colaboradores do Grupo Buonny conferirem.<\/p>\n<p>\u00c9 essencial compreender e estar de acordo com todas as instru\u00e7\u00f5es definidas no C\u00f3digo para que todos n\u00f3s tenhamos um ambiente de trabalho positivo e proveitoso. Caso possua alguma sugest\u00e3o ou den\u00fancia, <a href=\"http:\/\/info.buonny.com.br\/index.php\/portal-compliance\/contato\/\">entre em contato com o compliance.<\/a><\/p>\n<p>Fique atento \u00e0s nossas pr\u00f3ximas dicas dessa semana para melhorarmos ainda mais o nosso\u00a0ambiente de trabalho. Lembre-se:\u00a0<b>juntos somos muito mais fortes!<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nas instala\u00e7\u00f5es do grupo Buonny, voc\u00ea encontrar\u00e1 placas e outras sinaliza\u00e7\u00f5es nos ambientes de trabalho que tem como objetivo alertar, voc\u00ea e os visitantes no local, sobre os riscos existentes ali e outras informa\u00e7\u00f5es imprescind\u00edveis para seguran\u00e7a no local. \u00a0Fique atento \u00e0 todas as sinaliza\u00e7\u00f5es para garantir a sua seguran\u00e7a em casos de emerg\u00eancia. Em &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,63,45],"tags":[],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13225"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13225"}],"version-history":[{"count":1,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13225\/revisions"}],"predecessor-version":[{"id":13227,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13225\/revisions\/13227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/13226"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}