{"id":13545,"date":"2018-10-04T15:05:02","date_gmt":"2018-10-04T18:05:02","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=13545"},"modified":"2020-01-07T11:34:16","modified_gmt":"2020-01-07T13:34:16","slug":"aniversariantes-outubro-de-2018","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/aniversariantes-do-mes\/aniversariantes-outubro-de-2018\/","title":{"rendered":"Aniversariantes: Outubro de 2018"},"content":{"rendered":"<p>[vc_row][vc_column][vc_text_separator title=&#8221;Parab\u00e9ns ao aniversariantes de Outubro&#8221; color=&#8221;blue&#8221; el_class=&#8221;parabens&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_tta_accordion shape=&#8221;square&#8221; color=&#8221;sky&#8221; active_section=&#8221;1&#8243;][vc_tta_section title=&#8221;Libra \/ 23 de setembro &#8211; 22 de outubro&#8221; tab_id=&#8221;1442582655572-bfe1ff17-1aab7a41-5139d46e-587e&#8221;][vc_column_text css=&#8221;.vc_custom_1538675988051{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: rgba(224,224,224,0.22) !important;*background-color: rgb(224,224,224) !important;}&#8221;]<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra.png\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-6037 size-thumb_94x72 alignleft\" src=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-94x72.png\" alt=\"\" width=\"94\" height=\"72\" srcset=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-94x72.png 94w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-527x400.png 527w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-380x285.png 380w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-275x210.png 275w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-188x144.png 188w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/libra-200x150.png 200w\" sizes=\"(max-width: 94px) 100vw, 94px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Libra<em><br \/>\n<\/em><\/strong>Libra \/ 23 de setembro &#8211; 22 de outubro<\/p>\n<p class=\"western\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">O signo de Libra, \u00e9 marcado por seu equil\u00edbrio, gosta de sempre equilibrar as coisas, n\u00e3o desagradar ningu\u00e9m e ver o bem de todos.Devido a isso, outra caracter\u00edstica do libriano \u00e9 ser muito amigo, tenta ajudar a todos, faz amizade f\u00e1cil e gosta de estar rodeado de amigos.<\/span><\/span><\/span><\/p>\n<p class=\"western\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Por conta de seu equil\u00edbrio e sempre querer o bem de todos a sua volta, o libriano \u00e9 conhecido por ser indeciso em suas decis\u00f5es e dependentes das pessoas que os rodeia.<\/span><\/span><\/span><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Escorpi\u00e3o \/ 22 de outubro &#8211; 21 de novembro&#8221; tab_id=&#8221;1442583094632-1061c8ef-b5337a41-5139d46e-587e&#8221;][vc_column_text css=&#8221;.vc_custom_1442583262569{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: rgba(224,224,224,0.22) !important;*background-color: rgb(224,224,224) !important;}&#8221;]<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o.png\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-6034 size-thumb_94x72 alignleft\" src=\"http:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-94x72.png\" alt=\"\" width=\"94\" height=\"72\" srcset=\"https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-94x72.png 94w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-527x400.png 527w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-380x285.png 380w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-275x210.png 275w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-188x144.png 188w, https:\/\/info.buonny.com.br\/wp-content\/uploads\/2015\/08\/escorpi\u00e3o-200x150.png 200w\" sizes=\"(max-width: 94px) 100vw, 94px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Escorpi\u00e3o<em><br \/>\n<\/em><\/strong><em>22 de outubro\u00a0&#8211; 21 de\u00a0novembro<\/em><\/p>\n<p class=\"western\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">A principal caracter\u00edstica de Escorpi\u00e3o \u00e9 o mist\u00e9rio.As pessoas desses signo s\u00e3o misteriosas e muito observadoras. S\u00e3o intensas e gostam de viver grandes emo\u00e7\u00f5es.<\/span><\/span><\/span><\/p>\n<p class=\"western\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00c9 o signo mais inteligente emocionalmente, consegue lidar bem com perdas e decep\u00e7\u00f5es.<\/span><\/span><\/span><\/p>\n<p class=\"western\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Apesar de misteriosos, conseguem conviver bem com as pessoas.<\/span><\/span><\/span><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<table id=\"tablepress-109\" class=\"tablepress tablepress-id-109\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">DATA<\/th><th class=\"column-2\">COLABORADOR<\/th><th class=\"column-3\">DPTO<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Antonio Clovis<\/td><td class=\"column-3\">OPER - PAGR - A\u00c7O CAUCAIA<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Rodrigo Alves Gon\u00e7alves<\/td><td class=\"column-3\">OPER - OPS - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Rodrigo Gabriel dos Santos<\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Rafael dos Santos Fialho<\/td><td class=\"column-3\">ADM - PROCESSOS<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">Renata Figueiredo <\/td><td class=\"column-3\">ADM - AFASTADOS<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">Eurico Cabral <\/td><td class=\"column-3\">OPER - BSAT INT - GPA  <\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">Rubilene Souza <\/td><td class=\"column-3\">OPER - CAT - CENTRAL ROYAL <\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">Luciana Louren\u00e7o<\/td><td class=\"column-3\">ADM - QUALIDADE<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">Caroline Montalv\u00e3o<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS       <\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">Wadson Augusto Oliveira<\/td><td class=\"column-3\">OPER - PAGR - ADM BRASIL UBERLANDIA <\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">Sandra Alves Leite<\/td><td class=\"column-3\">OPER - BSAT EXT - ELOG BARUERI<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">Luiz Felipe Almeida<\/td><td class=\"column-3\">OPER - TLC - PESQUISA               <\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">Thiago Figueiredo Nogueira<\/td><td class=\"column-3\">LIDER BRASIL - ADM OPERACIONAL<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">Manoel Vieira Domingos<\/td><td class=\"column-3\">OPER - NSPI - PRONTA RESPOSTA<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">Alberto Carlos de Melo<\/td><td class=\"column-3\">SOLEN - ADMINISTRATIVO<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">Juliano Caillot<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS       <\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">Thomas de Ramos<\/td><td class=\"column-3\">OPER - BSAT EXT - VIA VAREJO JUNDIA\u00cd<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">Alessandra Santos <\/td><td class=\"column-3\">OPER - BSAT EXT - DIA GUARULHOS     <\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">Adriana Ribeiro dos Santos<\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">Adriano Amorosino Viana<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS <\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">William Avelino Cunha<\/td><td class=\"column-3\">OPER - BSAT - CHECKLIST<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">Thayna Siqueira Sampaio<\/td><td class=\"column-3\">GREEN - ADM<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">Andressa Luca Nascimento<\/td><td class=\"column-3\">RH HEALTH - OPERA\u00c7\u00d5ES<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">Douglas Jeremias de Paula<\/td><td class=\"column-3\">OPER - PAGR - BRASKEM S\u00c3O PAULO<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">Eduardo Ben-Hur<\/td><td class=\"column-3\">ADM - PROCESSOS<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">Davi Peres Souza<\/td><td class=\"column-3\">OPER - OPS - MONITORAMENTO          <\/td>\n<\/tr>\n<tr class=\"row-28 even\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">Sandra Lucia Duarte<\/td><td class=\"column-3\">RH HEALTH - COMERCIAL<\/td>\n<\/tr>\n<tr class=\"row-29 odd\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">Joao Vinicius Fugulin<\/td><td class=\"column-3\">ADM - FINANCEIRO<\/td>\n<\/tr>\n<tr class=\"row-30 even\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">Paulo Cesar Verissimo<\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO         <\/td>\n<\/tr>\n<tr class=\"row-31 odd\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">Gilson Nascimento<\/td><td class=\"column-3\">OPER - CBQ - TREINAMENTO            <\/td>\n<\/tr>\n<tr class=\"row-32 even\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">Davyd Wandell Xavier<\/td><td class=\"column-3\">OPER - BSAT EXT - DIA GUARULHOS<\/td>\n<\/tr>\n<tr class=\"row-33 odd\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Marcelo Teixeira de Souza<\/td><td class=\"column-3\">COM - VENDAS<\/td>\n<\/tr>\n<tr class=\"row-34 even\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Abraao Simao da Silva<\/td><td class=\"column-3\">OPER - OPS - MONITORAMENTO          <\/td>\n<\/tr>\n<tr class=\"row-35 odd\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">William Rocha Soares<\/td><td class=\"column-3\">OPER - CENTRAL DE SINISTROS - SOMPO <\/td>\n<\/tr>\n<tr class=\"row-36 even\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">Wagner Alves da Silva <\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO         <\/td>\n<\/tr>\n<tr class=\"row-37 odd\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">Rafael Rodrigues de Sousa<\/td><td class=\"column-3\">OPER - TLC - CONSULTA <\/td>\n<\/tr>\n<tr class=\"row-38 even\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">Marcos Diego dos Santos<\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-39 odd\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">Inaldo de Lima Galv\u00e3o<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS<\/td>\n<\/tr>\n<tr class=\"row-40 even\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">Carlos Eduardo Helu Luccas<\/td><td class=\"column-3\">ADM - CONTROLADORIA<\/td>\n<\/tr>\n<tr class=\"row-41 odd\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">Silvia Regina Figueiredo<\/td><td class=\"column-3\">ADM - FINANCEIRO<\/td>\n<\/tr>\n<tr class=\"row-42 even\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">Kevein Marchiotto Mendes<\/td><td class=\"column-3\">OPER - BSAT INT - TOKIO MARINE      <\/td>\n<\/tr>\n<tr class=\"row-43 odd\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">Sueli Bueno Alves<\/td><td class=\"column-3\">OPER - CAT - CENTRAL ROYAL<\/td>\n<\/tr>\n<tr class=\"row-44 even\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">Katy Elaine Parada<\/td><td class=\"column-3\">ADM - AFASTADOS<\/td>\n<\/tr>\n<tr class=\"row-45 odd\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">Maria Roberto Romao<\/td><td class=\"column-3\">TIC - TELECOM - BTECSYS<\/td>\n<\/tr>\n<tr class=\"row-46 even\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">Anayale Ribeiro<\/td><td class=\"column-3\">ADM - RECURSOS HUMANOS<\/td>\n<\/tr>\n<tr class=\"row-47 odd\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">Marcio da Silva Santos <\/td><td class=\"column-3\">OPER - OPS - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-48 even\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">Andrea de Campos Silva<\/td><td class=\"column-3\">OPER - BSAT INT - TOKIO MARINE<\/td>\n<\/tr>\n<tr class=\"row-49 odd\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">Patricia de Andrade Silva<\/td><td class=\"column-3\">ADM - AFASTADOS<\/td>\n<\/tr>\n<tr class=\"row-50 even\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">Daniel Viana do Nascimento<\/td><td class=\"column-3\">TIC - DESENVOLVIMENTO - BTECSYS<\/td>\n<\/tr>\n<tr class=\"row-51 odd\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">Fabio Luis da Silva<\/td><td class=\"column-3\">OPER - BSAT EXT - VIA VAREJO JUNDIAI<\/td>\n<\/tr>\n<tr class=\"row-52 even\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">Bruno Barbosa da Silva<\/td><td class=\"column-3\">OPER - BSAT INT - TOKIO MARINE<\/td>\n<\/tr>\n<tr class=\"row-53 odd\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">Josenir Pereira<\/td><td class=\"column-3\">OPER - BSAT INT - GPA<\/td>\n<\/tr>\n<tr class=\"row-54 even\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">Ana Gabriela Valentim<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS<\/td>\n<\/tr>\n<tr class=\"row-55 odd\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">Cristiane Braga de Macedo<\/td><td class=\"column-3\">OPER - BSAT - MONITORAMENTO<\/td>\n<\/tr>\n<tr class=\"row-56 even\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">Daniella da Silva Assis<\/td><td class=\"column-3\">ADM - AFASTADOS<\/td>\n<\/tr>\n<tr class=\"row-57 odd\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">Guilherme Scartezini <\/td><td class=\"column-3\">OPER - TLC - AGREGADOS<\/td>\n<\/tr>\n<tr class=\"row-58 even\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">Claudia Valeria Leite<\/td><td class=\"column-3\">OPER - CAT - CENTRAL ROYAL<\/td>\n<\/tr>\n<tr class=\"row-59 odd\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">Douglas Camilo Bastos <\/td><td class=\"column-3\">OPER - OPS - GEST\u00c3O E ADMINISTRA\u00c7\u00c3O<\/td>\n<\/tr>\n<tr class=\"row-60 even\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">Vanine Vanina Gallo<\/td><td class=\"column-3\">ADM - QUALIDADE - ATENDIMENTO<\/td>\n<\/tr>\n<tr class=\"row-61 odd\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">Ednaldo de Souza Ramos<\/td><td class=\"column-3\">SOLEN - ADMINISTRATIVO<\/td>\n<\/tr>\n<tr class=\"row-62 even\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">Emerson Pereira<\/td><td class=\"column-3\">OPER - BSAT EXT - LG CAJAMAR <\/td>\n<\/tr>\n<tr class=\"row-63 odd\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">Eduarda Rodrigues Barbosa<\/td><td class=\"column-3\">RH HEALTH - COMERCIAL<\/td>\n<\/tr>\n<tr class=\"row-64 even\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">Alessandro da Silva<\/td><td class=\"column-3\">OPER - TLC - CONSULTA<\/td>\n<\/tr>\n<tr class=\"row-65 odd\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">Andre Luiz de Brito<\/td><td class=\"column-3\">OPER - BSAT EXT - SOMPO<\/td>\n<\/tr>\n<tr class=\"row-66 even\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">Caio Cezario Azevedo<\/td><td class=\"column-3\">OPER - IGR - GEST\u00c3O DE CONTAS<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-109 from cache -->[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O signo de Libra, \u00e9 marcado por seu equil\u00edbrio, gosta de sempre equilibrar as coisas, n\u00e3o desagradar ningu\u00e9m e ver o bem de todos.Devido a isso, outra caracter\u00edstica do libriano \u00e9 ser muito amigo, tenta ajudar a todos, faz amizade f\u00e1cil e gosta de estar rodeado de amigos.<\/p>\n","protected":false},"author":1,"featured_media":13068,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[50],"tags":[],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13545"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13545"}],"version-history":[{"count":2,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13545\/revisions"}],"predecessor-version":[{"id":16638,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13545\/revisions\/16638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/13068"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}