{"id":16671,"date":"2020-01-17T13:35:21","date_gmt":"2020-01-17T15:35:21","guid":{"rendered":"http:\/\/info.buonny.com.br\/?p=16671"},"modified":"2020-01-17T13:45:39","modified_gmt":"2020-01-17T15:45:39","slug":"couromoda-2020-buonny-marca-presenca","status":"publish","type":"post","link":"https:\/\/info.buonny.com.br\/index.php\/acontece\/couromoda-2020-buonny-marca-presenca\/","title":{"rendered":"Couromoda 2020: Buonny marca presen\u00e7a"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]A Buonny n\u00e3o para no tempo. A empresa sempre busca novas oportunidades para levar suas solu\u00e7\u00f5es para empresas de diversos segmentos de mercado e, por isso, marcamos presen\u00e7a na principal feira de neg\u00f3cios do setor cal\u00e7adista no Brasil, a Couromoda.<\/p>\n<p>A feira reuniu como expositores os principais fabricantes brasileiros de cal\u00e7ados, al\u00e9m de fornecedores de equipamentos, servi\u00e7os, tecnologias voltadas para o setor, e atraiu muitos lojistas, compradores e exportadores que atuam em todas as partes do pa\u00eds.<\/p>\n<p>A edi\u00e7\u00e3o deste ano trouxe lan\u00e7amentos de mais de mil marcas, al\u00e9m de atra\u00e7\u00f5es como f\u00f3runs e palestras. Representando a Buonny, tivemos a visita realizada por dois integrantes da nossa equipe comercial, Sidney Leite e Renata Leonardo.\u00a0\u201cNossa presen\u00e7a em eventos como a feira Couromoda \u00e9 essencial para prestigiar os nossos clientes e parceiros, pois contribui\u00a0para a cria\u00e7\u00e3o de uma rela\u00e7\u00e3o de confian\u00e7a entre nossas empresas&#8221;, explica a coordenadora comercial, Katia Abade.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid element_width=&#8221;3&#8243; initial_loading_animation=&#8221;fadeIn&#8221; grid_id=&#8221;vc_gid:1579275316633-85eba574-1749-0&#8243; include=&#8221;16674,16675,16676,16677,16678,16679,16680,16681,16682,16683,16684,16685&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edi\u00e7\u00e3o deste ano da principal feira do segmento cal\u00e7adista do Brasil recebe a visita da Buonny.<\/p>\n","protected":false},"author":1,"featured_media":16689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[52,406,64,387],"tags":[],"_links":{"self":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16671"}],"collection":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16671"}],"version-history":[{"count":2,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16671\/revisions"}],"predecessor-version":[{"id":16686,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16671\/revisions\/16686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media\/16689"}],"wp:attachment":[{"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.buonny.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}